{"id":542,"date":"2008-09-25T09:02:07","date_gmt":"2008-09-25T08:02:07","guid":{"rendered":"http:\/\/www.web-3-null.de\/index.php\/allgemein\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen.html"},"modified":"2008-09-25T09:02:07","modified_gmt":"2008-09-25T08:02:07","slug":"ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen","status":"publish","type":"post","link":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/","title":{"rendered":"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen"},"content":{"rendered":"<p>Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden.<\/p>\n<p>Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich bislang sehr verschlossen und nahm nicht an IVW (analog Reichweite Zeitschriftenauflage, kennen Sie vielleicht aus dem Impressum bei einer Zeitschrift) oder den Messungen der AGOF &#8211; Arbeitsgemeinschaft Online-Forschung e.v. teil.<\/p>\n<p>Die Kombination aus Google Trends und Google Ad Planner sieht die Angebote laut verschiedenen Quellen in den Top 20 der deutschen Internetseiten. Nicht nur die jeweiligen Hauptseiten kommen dabei sehr gut weg, auch beispielsweise die Tagesschau mit ihrer eigenen Seite oder einzelne Sendeanstalten sind sehr gut platziert. Wohlgemerkt finanziert aus den Geldern der Geb\u00fchrenzahler.<\/p>\n<p>Es geht sogar so weit, dass die \u00d6ffentlich-Rechtlichen Werbung f\u00fcr ihre Internetangebote auf GMX schalten, was nun wirklich nicht billig ist. Und dass in vielen Sendungen der Hinweis auf weiterf\u00fchrende Informationen mit Angabe der URL kommt, ist mittlerweile Standard. Auch geb\u00fchrenfinanziert.<\/p>\n<p>Dass der europ\u00e4ische Verband der (privaten) Verleger EPC derweil nachhaltig sauer ist, kann nachvollzogen werden. Immerhin gibt es keine Gelder aus staatlich lizensierter Quelle und die Privaten tragen das volle Risiko. Auch der EU-Kommission war die Verwendung der Geb\u00fchren schon \u00fcbel aufgesto\u00dfen. Neelie Kroes, die EU-Kommissarin, nimmt schon seit l\u00e4ngerem die <a title=\"Internetangebote ARD und ZDF\" href=\"http:\/\/www.web-3-null.de\/index.php\/allgemein\/zoff-um-die-internetangebote-von-ard-und-zdf.html\">Internetangebote ARD und ZDF<\/a> unter die Lupe.<\/p>\n<p>Der Pr\u00e4sident des europ\u00e4ischen Verlegerverbandes sch\u00e4tzt derweil, dass irgendwann die Verbraucher auf die Barrikaden gehen. Es ist wohl auch ein wenig Wunschdenken dabei. Weiter unten das Statement im Original. Die deutsche Politik hat sich fest vorgenommen, das Problem anzugehen und bastelt munter &#8211; manche meinen unqualifiziert &#8211; an Restriktionen f\u00fcr geb\u00fchrenfinanzierte Internetangebote deluxe.<\/p>\n<p>Am 22. Oktober treffen sich die Bundesl\u00e4nder, um abzustimmen, was ARD und ZDF mit unseren Rundfunkgeb\u00fchren machen d\u00fcrfen &#8211; und vor allem: was nicht. Derweil gibt es eine muntere Meinungsmache von allen Seiten.<\/p>\n<p>Statement innerhalb einer Presseinfo vom EPC:<\/p>\n<p>In the context of the European Commission\u2019s current review of state aid rules for public service broadcasters (PSBs), Francisco Pinto Balsem\u00e3o, Chairman of the European Publishers Council (EPC) and Chairman and CEO of Impresa in Portugal has called for PSBs to be redefined and radically changed in line with the realities of modern broadcasting and convergent communications.<\/p>\n<p>Speaking at a major industry conference on the future of public service broadcasting (PSB) hosted in Helsinki by the Helsingin Sanomat Foundation, Mr Balsemao said: \u201cPSBs have acted as though they were commercial players and have established strong, even dominant positions while using public money.\u00a0 PSBs are now major publishers online (and sometimes in print and on radio) competing head to head with commercial newspapers and magazines.\u00a0 Public and private broadcasters compete with both broadcast and non-broadcast content, as consumers choose to watch or download movies and TV output via the Internet and\u00a0 Mobiles.<\/p>\n<p>\u201cFor years we in the private sector have challenged the way the PSBs have distorted the market\u2026but Governments have not been prepared to bring them to heel.\u201d<\/p>\n<p>Mr Balsem\u00e3o warned that consumers might well refuse to pay the licence fee: \u201cConsumers not politicians will be the driving force to end PSB public funding throughout Europe over the next 10-20 years\u2026.Why should viewers in any country be required by Law to pay for what they may not watch?<\/p>\n<p>Mr Balsem\u00e3o suggested that \u201cfuture PSBs will be smaller and leaner, dedicated to high-quality programming funded mainly by sponsorship or subscription. If they wish to maintain any degree of public funding, they need the support of viewers. In order to do this they must be programme led:\u00a0 hot houses of talent and creative energy \u2013 machines to make and commission programmes and to earn or raise money to make more.\u201d He insisted on a role for PSBs, but only under new parameters subject to independent regulation, and on the condition that they earn their own keep and raise standards within the boundaries of fair competition.\u00a0 An example would be to take elements from the US model where local TV (PBS ) and Radio (NPR) stations develop their own programme schedules within networks. Some programming is local, some nationally commissioned with some core funding from Government but with most funds coming from individuals, foundations, companies, subscriptions and sponsorship.<\/p>\n<p>Note: In terms of timing of the EU-led PSB review, the Commission launched a consultation earlier this year to which the EPC responded.\u00a0 Since the March deadline, the Commission has been assessing the responses. Commissioner Kroes spoke at a French Presidency conference on the issue in July.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.web-3-null.de%2Findex.php%2Fard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.web-3-null.de%2Findex.php%2Fard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen%2F&text=ARD%20und%20ZDF%20%E2%80%93%20umfangreiche%20Internetangebote%20erstmals%20mit%20Zahlen\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.web-3-null.de%2Findex.php%2Fard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen%2F%20ARD%20und%20ZDF%20%E2%80%93%20umfangreiche%20Internetangebote%20erstmals%20mit%20Zahlen\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.web-3-null.de%2Findex.php%2Fard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich &hellip; <a href=\"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1,3],"tags":[],"class_list":["post-542","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-web-10"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Georg Grohs Online Marketing\"\/>\n\t<meta name=\"google-site-verification\" content=\"mZwpNWpN1paSAtYbBBPjMOLFPiuzHD7o_VvNc5N4wUw\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Web 3.0 | Next Generation Marketing - Online Marketing Experten und Gel\u00e4ster\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0\" \/>\n\t\t<meta property=\"og:description\" content=\"Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-09-25T08:02:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-09-25T08:02:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#article\",\"name\":\"ARD und ZDF \\u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0\",\"headline\":\"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen\",\"author\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/author\\\/gg\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/#organization\"},\"datePublished\":\"2008-09-25T09:02:07+02:00\",\"dateModified\":\"2008-09-25T09:02:07+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#webpage\"},\"articleSection\":\"Aktuelles, Web 1.0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.web-3-null.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.web-3-null.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Aktuelles\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"position\":2,\"name\":\"Aktuelles\",\"item\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/category\\\/allgemein\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#listItem\",\"name\":\"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.web-3-null.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#listItem\",\"position\":3,\"name\":\"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Aktuelles\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/#organization\",\"name\":\"Web 3.0\",\"description\":\"Next Generation Marketing - Online Marketing Experten und Gel\\u00e4ster\",\"url\":\"https:\\\/\\\/www.web-3-null.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/author\\\/gg\\\/#author\",\"url\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/author\\\/gg\\\/\",\"name\":\"Georg Grohs Online Marketing\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a96e9002a71190251ef8cb0d22b62c79ec744847ee70c213fe10115089dde67?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Georg Grohs Online Marketing\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#webpage\",\"url\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/\",\"name\":\"ARD und ZDF \\u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0\",\"description\":\"Die \\u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\\u00fcckgehalten. Das ist merkw\\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/author\\\/gg\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/index.php\\\/author\\\/gg\\\/#author\"},\"datePublished\":\"2008-09-25T09:02:07+02:00\",\"dateModified\":\"2008-09-25T09:02:07+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/#website\",\"url\":\"https:\\\/\\\/www.web-3-null.de\\\/\",\"name\":\"Web 3.0\",\"description\":\"Next Generation Marketing - Online Marketing Experten und Gel\\u00e4ster\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.web-3-null.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0","description":"Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich","canonical_url":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"mZwpNWpN1paSAtYbBBPjMOLFPiuzHD7o_VvNc5N4wUw","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#article","name":"ARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0","headline":"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen","author":{"@id":"https:\/\/www.web-3-null.de\/index.php\/author\/gg\/#author"},"publisher":{"@id":"https:\/\/www.web-3-null.de\/#organization"},"datePublished":"2008-09-25T09:02:07+02:00","dateModified":"2008-09-25T09:02:07+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#webpage"},"isPartOf":{"@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#webpage"},"articleSection":"Aktuelles, Web 1.0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.web-3-null.de#listItem","position":1,"name":"Home","item":"https:\/\/www.web-3-null.de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.web-3-null.de\/index.php\/category\/allgemein\/#listItem","name":"Aktuelles"}},{"@type":"ListItem","@id":"https:\/\/www.web-3-null.de\/index.php\/category\/allgemein\/#listItem","position":2,"name":"Aktuelles","item":"https:\/\/www.web-3-null.de\/index.php\/category\/allgemein\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#listItem","name":"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.web-3-null.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#listItem","position":3,"name":"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen","previousItem":{"@type":"ListItem","@id":"https:\/\/www.web-3-null.de\/index.php\/category\/allgemein\/#listItem","name":"Aktuelles"}}]},{"@type":"Organization","@id":"https:\/\/www.web-3-null.de\/#organization","name":"Web 3.0","description":"Next Generation Marketing - Online Marketing Experten und Gel\u00e4ster","url":"https:\/\/www.web-3-null.de\/"},{"@type":"Person","@id":"https:\/\/www.web-3-null.de\/index.php\/author\/gg\/#author","url":"https:\/\/www.web-3-null.de\/index.php\/author\/gg\/","name":"Georg Grohs Online Marketing","image":{"@type":"ImageObject","@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/8a96e9002a71190251ef8cb0d22b62c79ec744847ee70c213fe10115089dde67?s=96&d=mm&r=g","width":96,"height":96,"caption":"Georg Grohs Online Marketing"}},{"@type":"WebPage","@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#webpage","url":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/","name":"ARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0","description":"Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.web-3-null.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/#breadcrumblist"},"author":{"@id":"https:\/\/www.web-3-null.de\/index.php\/author\/gg\/#author"},"creator":{"@id":"https:\/\/www.web-3-null.de\/index.php\/author\/gg\/#author"},"datePublished":"2008-09-25T09:02:07+02:00","dateModified":"2008-09-25T09:02:07+02:00"},{"@type":"WebSite","@id":"https:\/\/www.web-3-null.de\/#website","url":"https:\/\/www.web-3-null.de\/","name":"Web 3.0","description":"Next Generation Marketing - Online Marketing Experten und Gel\u00e4ster","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.web-3-null.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Web 3.0 | Next Generation Marketing - Online Marketing Experten und Gel\u00e4ster","og:type":"article","og:title":"ARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0","og:description":"Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich","og:url":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/","article:published_time":"2008-09-25T08:02:07+00:00","article:modified_time":"2008-09-25T08:02:07+00:00","twitter:card":"summary","twitter:title":"ARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen | Web 3.0","twitter:description":"Die \u00d6ffentlich-Rechtlichen Anstalten haben sich bisher mit Zugriffszahlen auf Ihre Websites stark zur\u00fcckgehalten. Das ist merkw\u00fcrdig, weil beispielsweise Reichweiten der Sender gerne und oft publiziert werden. Jetzt kommt so sukzessive heraus, was denn ARD und ZDF von den Geb\u00fchren der Fernsehzuschauer alles an Reichweite im Internet haben. Im Gegensatz zu privaten Anbietern gab man sich"},"aioseo_meta_data":{"post_id":"542","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-26 11:54:35","updated":"2026-02-25 08:15:45","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.web-3-null.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.web-3-null.de\/index.php\/category\/allgemein\/\" title=\"Aktuelles\">Aktuelles<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tARD und ZDF \u2013 umfangreiche Internetangebote erstmals mit Zahlen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.web-3-null.de"},{"label":"Aktuelles","link":"https:\/\/www.web-3-null.de\/index.php\/category\/allgemein\/"},{"label":"ARD und ZDF &#8211; umfangreiche Internetangebote erstmals mit Zahlen","link":"https:\/\/www.web-3-null.de\/index.php\/ard-und-zdf-umfangreiche-internetangebote-erstmals-mit-zahlen\/"}],"_links":{"self":[{"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/posts\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/comments?post=542"}],"version-history":[{"count":0,"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/posts\/542\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/media?parent=542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/categories?post=542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.web-3-null.de\/index.php\/wp-json\/wp\/v2\/tags?post=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}